{"id":10761,"date":"2019-02-09T18:07:29","date_gmt":"2019-02-09T18:07:29","guid":{"rendered":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia.jpg"},"modified":"2019-02-09T18:08:46","modified_gmt":"2019-02-09T18:08:46","slug":"abey-ahmed-bill-gates-in-ethiopia","status":"inherit","type":"attachment","link":"https:\/\/www.ephremtube.com\/galleries\/ethiopian-political-leaders\/abey-ahmed-bill-gates-in-ethiopia\/","title":{"rendered":"Dr Abey Ahmed and Bill Gates in Ethiopia"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-10761","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"Dr Abey Ahmed and Bill Gates in Ethiopia\" srcset=\"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-300x200.jpg 300w, https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-768x512.jpg 768w, https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-900x600.jpg 900w, https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-600x400.jpg 600w, https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-30x20.jpg 30w, https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ethiopian prime minister Dr Abey Ahmed and Bill Gates in Addis Ababa, Ethiopia | 2019<\/p>\n"},"caption":{"rendered":"<p>Dr Abey Ahmed and Bill Gates<\/p>\n"},"alt_text":"Dr Abey Ahmed and Bill Gates in Ethiopia","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":640,"file":"2015\/05\/abey-ahmed-bill-gates-in-ethiopia.jpg","filesize":79527,"sizes":{"medium":{"file":"abey-ahmed-bill-gates-in-ethiopia-300x200.jpg","width":300,"height":200,"filesize":45120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-300x200.jpg"},"thumbnail":{"file":"abey-ahmed-bill-gates-in-ethiopia-150x150.jpg","width":150,"height":150,"filesize":24967,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-150x150.jpg"},"medium_large":{"file":"abey-ahmed-bill-gates-in-ethiopia-768x512.jpg","width":768,"height":512,"filesize":158622,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-768x512.jpg"},"post-thumbnail":{"file":"abey-ahmed-bill-gates-in-ethiopia-300x200.jpg","width":300,"height":200,"filesize":45120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-300x200.jpg"},"moon-slider-thumbs-square":{"file":"abey-ahmed-bill-gates-in-ethiopia-300x300.jpg","width":300,"height":300,"filesize":54512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-300x300.jpg"},"moon-half-size":{"file":"abey-ahmed-bill-gates-in-ethiopia-900x600.jpg","width":900,"height":600,"filesize":205310,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-900x600.jpg"},"moon-third-size":{"file":"abey-ahmed-bill-gates-in-ethiopia-600x400.jpg","width":600,"height":400,"filesize":115720,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-600x400.jpg"},"moon-fourth-size":{"file":"abey-ahmed-bill-gates-in-ethiopia-300x200.jpg","width":300,"height":200,"filesize":45120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-300x200.jpg"},"moon-micro-thumbnail":{"file":"abey-ahmed-bill-gates-in-ethiopia-30x20.jpg","width":30,"height":20,"filesize":10150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-30x20.jpg"},"woocommerce_thumbnail":{"file":"abey-ahmed-bill-gates-in-ethiopia-300x300.jpg","width":300,"height":300,"filesize":22316,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"abey-ahmed-bill-gates-in-ethiopia-100x100.jpg","width":100,"height":100,"filesize":11972,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-100x100.jpg"},"woocommerce_single":{"file":"abey-ahmed-bill-gates-in-ethiopia-600x400.jpg","width":600,"height":400,"filesize":39266,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia-600x400.jpg"},"full":{"file":"abey-ahmed-bill-gates-in-ethiopia.jpg","width":960,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":149,"source_url":"https:\/\/www.ephremtube.com\/galleries\/wp-content\/uploads\/2015\/05\/abey-ahmed-bill-gates-in-ethiopia.jpg","filename":"abey-ahmed-bill-gates-in-ethiopia.jpg","filesize":79527,"_links":{"self":[{"href":"https:\/\/www.ephremtube.com\/galleries\/wp-json\/wp\/v2\/media\/10761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ephremtube.com\/galleries\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.ephremtube.com\/galleries\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.ephremtube.com\/galleries\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ephremtube.com\/galleries\/wp-json\/wp\/v2\/comments?post=10761"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":149,"href":"https:\/\/www.ephremtube.com\/galleries\/wp-json\/wp\/v2\/posts\/149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}